{"id":127,"date":"2017-12-19T15:03:11","date_gmt":"2017-12-19T15:03:11","guid":{"rendered":"https:\/\/www.wromwrom.net\/die-wromwrom-net-roadmap-september-ausgabe\/"},"modified":"2018-01-09T15:02:10","modified_gmt":"2018-01-09T15:02:10","slug":"die-wromwrom-net-roadmap-september-ausgabe","status":"publish","type":"post","link":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/","title":{"rendered":"Die WromWrom.net Roadmap, September-Ausgabe"},"content":{"rendered":"<p>Da sind wir, einen Monat sp\u00e4ter. Mal sehen, welche Versprechen wir halten konnten<\/p>\n<p><strong>Logo und CI-Farben<\/strong><br \/>\nDaran arbeiten wir noch. Der Tiger ist fast fertig, jetzt machen wir den Drachen zu, und dann auf zur Wortmarke.<br \/>\nWir werden hoffentlich n\u00e4chsten Monat mehr haben.<\/p>\n<p><strong>Alternative LogIns<\/strong><br \/>\nWir haben WromWrom.net so eingerichtet, dass ihr euch \u00fcber Steam, Windows live, Google\/YouTube, FaceBook, Twitter, Tumblr und Instagram registrieren und einloggen k\u00f6nnt und suchen nach einer M\u00f6glichkeit, dies auch \u00fcber das Playstation Network zu erm\u00f6glichen. Letzteres kann eine Weile dauern.<br \/>\nWir nehmen so viele Informationen vom bestehenden Profil auf, wie ihr uns erlaubt, um das Profil bei WromWrom zu f\u00fcllen, so dass ihr nicht alles zweimal schreiben m\u00fcsst.<br \/>\nDar\u00fcber hinaus k\u00f6nnt ihr eure Kontakte importieren. Wenn die bereits Mitglieder von WromWrom sind, k\u00f6nnt ihr auch hier Freunde werden!<\/p>\n<p><strong>Freunde finden<\/strong><br \/>\nAbsolut m\u00f6glich im Moment, ihr k\u00f6nnt sogar eine kleine Nachricht dazu hinzuf\u00fcgen.<\/p>\n<p><strong>Artikel und Interaktion<\/strong><br \/>\nNun, das ist bereits ein Artikel, und ihr k\u00f6nnt es kommentieren, also sind wir auch hier gut aufgehoben.<\/p>\n<p>Und was haben wir f\u00fcr Oktober geplant?<\/p>\n<p>Kalender-Integration<br \/>\nStrecken- und Fahrzeugdatenbank<br \/>\nUp- und Downvote von Inhalten<br \/>\nBenutzer- und Fahrerrangliste<\/p>\n<p>Das war&#8217;s f\u00fcr heute. Aber es gibt noch viel mehr in unserer Roadmap, die Folgendes beinhaltet:<\/p>\n<p>Bessere Interaktion in der Gemeinschaft<br \/>\nAufbau von Renn-ligen, Rennclubs und was auch immer f\u00fcr M\u00f6glichkeiten ihr haben m\u00f6chtet, um zusammenzukommen.<br \/>\nAufbau einer umfangreichen Datenbank von Strecken und Autos, die f\u00fcr alle m\u00f6glichen Sims verf\u00fcgbar sind, einschlie\u00dflich Mods und Mod-Downloads.<br \/>\nEinrichten und Starten eines Sim-Servers aus dem von WromWrom.net heraus.<br \/>\nund viele, viele weitere Ideen. Vielleicht mit DEINER Idee!<\/p>\n<p>Bitte kommentiert munter alles, was ihr seht, und gebt uns auf jeden Fall eure Meinung zu dem, was ihr auf WromWrom.net sehen m\u00f6chtet, sowie Ideen. Wir versprechen, alles zu lesen und jede Idee zu ber\u00fccksichtigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da sind wir, einen Monat sp\u00e4ter. Mal sehen, welche Versprechen wir halten konnten Logo und CI-Farben Daran arbeiten wir noch. Der Tiger ist fast fertig, jetzt machen wir den Drachen zu, und dann auf zur Wortmarke. Wir werden hoffentlich n\u00e4chsten Monat mehr haben. Alternative LogIns Wir haben WromWrom.net so eingerichtet, dass ihr euch \u00fcber Steam, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[103],"tags":[],"class_list":["post-127","post","type-post","status-publish","format-standard","hentry","category-roadmap-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net\" \/>\n<meta property=\"og:description\" content=\"Da sind wir, einen Monat sp\u00e4ter. Mal sehen, welche Versprechen wir halten konnten Logo und CI-Farben Daran arbeiten wir noch. Der Tiger ist fast fertig, jetzt machen wir den Drachen zu, und dann auf zur Wortmarke. Wir werden hoffentlich n\u00e4chsten Monat mehr haben. Alternative LogIns Wir haben WromWrom.net so eingerichtet, dass ihr euch \u00fcber Steam, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/\" \/>\n<meta property=\"og:site_name\" content=\"WromWrom.net\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WromWrom.net\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-19T15:03:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-09T15:02:10+00:00\" \/>\n<meta name=\"author\" content=\"SertaFarenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wromwromracing\" \/>\n<meta name=\"twitter:site\" content=\"@wromwromracing\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SertaFarenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/\"},\"author\":{\"name\":\"SertaFarenz\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#\\\/schema\\\/person\\\/25d97f566149c358a5bcb190ab1a72f5\"},\"headline\":\"Die WromWrom.net Roadmap, September-Ausgabe\",\"datePublished\":\"2017-12-19T15:03:11+00:00\",\"dateModified\":\"2018-01-09T15:02:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#organization\"},\"articleSection\":[\"Roadmap\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/\",\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/\",\"name\":\"Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#website\"},\"datePublished\":\"2017-12-19T15:03:11+00:00\",\"dateModified\":\"2018-01-09T15:02:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/2017\\\/12\\\/die-wromwrom-net-roadmap-september-ausgabe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die WromWrom.net Roadmap, September-Ausgabe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/\",\"name\":\"WromWrom.net\",\"description\":\"Mad about Racing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#organization\",\"name\":\"WromWrom.net\",\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logobeta-1.png\",\"contentUrl\":\"https:\\\/\\\/www.wromwrom.net\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Logobeta-1.png\",\"width\":512,\"height\":165,\"caption\":\"WromWrom.net\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WromWrom.net\\\/\",\"https:\\\/\\\/x.com\\\/wromwromracing\",\"https:\\\/\\\/www.youtube.com\\\/WromWrom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/#\\\/schema\\\/person\\\/25d97f566149c358a5bcb190ab1a72f5\",\"name\":\"SertaFarenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wromwrom.net\\\/wp-content\\\/uploads\\\/heateor\\\/526354158696711.jpeg\",\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/wp-content\\\/uploads\\\/heateor\\\/526354158696711.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.wromwrom.net\\\/wp-content\\\/uploads\\\/heateor\\\/526354158696711.jpeg\",\"caption\":\"SertaFarenz\"},\"url\":\"https:\\\/\\\/www.wromwrom.net\\\/de\\\/author\\\/sertafarenz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/","og_locale":"de_DE","og_type":"article","og_title":"Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net","og_description":"Da sind wir, einen Monat sp\u00e4ter. Mal sehen, welche Versprechen wir halten konnten Logo und CI-Farben Daran arbeiten wir noch. Der Tiger ist fast fertig, jetzt machen wir den Drachen zu, und dann auf zur Wortmarke. Wir werden hoffentlich n\u00e4chsten Monat mehr haben. Alternative LogIns Wir haben WromWrom.net so eingerichtet, dass ihr euch \u00fcber Steam, [&hellip;]","og_url":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/","og_site_name":"WromWrom.net","article_publisher":"https:\/\/www.facebook.com\/WromWrom.net\/","article_published_time":"2017-12-19T15:03:11+00:00","article_modified_time":"2018-01-09T15:02:10+00:00","author":"SertaFarenz","twitter_card":"summary_large_image","twitter_creator":"@wromwromracing","twitter_site":"@wromwromracing","twitter_misc":{"Verfasst von":"SertaFarenz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/#article","isPartOf":{"@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/"},"author":{"name":"SertaFarenz","@id":"https:\/\/www.wromwrom.net\/de\/#\/schema\/person\/25d97f566149c358a5bcb190ab1a72f5"},"headline":"Die WromWrom.net Roadmap, September-Ausgabe","datePublished":"2017-12-19T15:03:11+00:00","dateModified":"2018-01-09T15:02:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/www.wromwrom.net\/de\/#organization"},"articleSection":["Roadmap"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/","url":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/","name":"Die WromWrom.net Roadmap, September-Ausgabe - WromWrom.net","isPartOf":{"@id":"https:\/\/www.wromwrom.net\/de\/#website"},"datePublished":"2017-12-19T15:03:11+00:00","dateModified":"2018-01-09T15:02:10+00:00","breadcrumb":{"@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.wromwrom.net\/de\/2017\/12\/die-wromwrom-net-roadmap-september-ausgabe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wromwrom.net\/de\/"},{"@type":"ListItem","position":2,"name":"Die WromWrom.net Roadmap, September-Ausgabe"}]},{"@type":"WebSite","@id":"https:\/\/www.wromwrom.net\/de\/#website","url":"https:\/\/www.wromwrom.net\/de\/","name":"WromWrom.net","description":"Mad about Racing","publisher":{"@id":"https:\/\/www.wromwrom.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wromwrom.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.wromwrom.net\/de\/#organization","name":"WromWrom.net","url":"https:\/\/www.wromwrom.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wromwrom.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.wromwrom.net\/wp-content\/uploads\/2017\/12\/Logobeta-1.png","contentUrl":"https:\/\/www.wromwrom.net\/wp-content\/uploads\/2017\/12\/Logobeta-1.png","width":512,"height":165,"caption":"WromWrom.net"},"image":{"@id":"https:\/\/www.wromwrom.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WromWrom.net\/","https:\/\/x.com\/wromwromracing","https:\/\/www.youtube.com\/WromWrom"]},{"@type":"Person","@id":"https:\/\/www.wromwrom.net\/de\/#\/schema\/person\/25d97f566149c358a5bcb190ab1a72f5","name":"SertaFarenz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wromwrom.net\/wp-content\/uploads\/heateor\/526354158696711.jpeg","url":"https:\/\/www.wromwrom.net\/wp-content\/uploads\/heateor\/526354158696711.jpeg","contentUrl":"https:\/\/www.wromwrom.net\/wp-content\/uploads\/heateor\/526354158696711.jpeg","caption":"SertaFarenz"},"url":"https:\/\/www.wromwrom.net\/de\/author\/sertafarenz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/posts\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":1,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/posts\/127\/revisions"}],"predecessor-version":[{"id":3298,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/posts\/127\/revisions\/3298"}],"wp:attachment":[{"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/media?parent=127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/categories?post=127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wromwrom.net\/de\/wp-json\/wp\/v2\/tags?post=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}